{"id":412,"date":"2008-07-01T17:44:00","date_gmt":"2008-07-01T16:44:00","guid":{"rendered":"https:\/\/giuseppepetruzzellis.com\/?p=412"},"modified":"2023-02-03T15:24:01","modified_gmt":"2023-02-03T14:24:01","slug":"motorshow-2008","status":"publish","type":"post","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/","title":{"rendered":"MotorShow <br>(2008)"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Motor Show\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/bQXsqR8sZ54?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Motor Show \u00e8 un film di montaggio prodotto da&nbsp;<a href=\"http:\/\/www.esterni.org\/\">esterni<\/a>&nbsp;e Giuseppe Petruzzellis. Un esperimento di comunicazione sociale che affronta il paradosso e il tab\u00f9 della velocit\u00e0 alla guida.<\/strong> <br>Le case automobilistiche pubblicizzano macchine sempre pi\u00f9 potenti, che hanno bisogno di 7 airbag per essere apparentemente pi\u00f9 sicure. Ma quando il telegiornale parla dei morti sulle strade raramente si sente dire a quanto andava chi ha causato l&#8217;incidente. <br>Perch\u00e9 correndo a centocinquanta all&#8217;ora viene da sentirsi forti e spavaldi, perch\u00e9 andare oltre i limiti \u00e8 una figata (fino a quando non succede niente). Che adrenalina quel rombo del motore, \u00e8 indescrivibile, eppure \u00e8 proprio la sensazione che si prova nell&#8217;essere potenziali pirati della strada. <br><br>Evento speciale al <strong>Milano Film Festival<\/strong> (2008). <br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gli italiani sono famosi nel mondo per la loro passione per i motori (oltre che per le donne). L&#8217;abilit\u00e0 nella guida e il brivido della velocit\u00e0 sono da tempo (dis)valori che accomunano trasversalmente strati sociali e generazioni diverse. Oltre ad essere una nazione di allenatori di calcio, ci vantiamo di essere anche una nazione di piloti. <br>L&#8217;origine di questa italica mania risale forse alla mitologia del Futurismo, quando nei primi anni del Novecento Marinetti e compagnia diedero il via all&#8217;esaltazione di quel ritrovato della modernit\u00e0 sfrecciante sulle quattro ruote. Allora si parlava di primitivi prototipi, quelle sferraglianti carrozze erano ancora poco diffuse, ma ben si prestavano a simboleggiare metaforicamente il progresso e il nuovo che avanza. A leggerli oggi per\u00f2 quei testi e quei manifesti sembrano molto naive. <br>Nel frattempo, seguendo lo sviluppo economico dell&#8217;industria automobilistica, l&#8217;oggetto macchina si \u00e8 trasformato in status symbol, effige di potere, rappresentazione di mascolinit\u00e0 e garanzia di sex appeal. Un oggetto desiderabile e desiderato, archetipo di successo e vitalit\u00e0\/virilit\u00e0, o almeno questi sono i capisaldi delle campagne pubblicitarie che spacciano macchine sempre pi\u00f9 nuove, potenti, sicure, affidabili, veloci. <br>Fin qui parrebbe essere ancora su piani poco distanti dall&#8217;estetica futurista: ma ormai abbiamo scoperto che le auto inquinano, e che, soprattutto, le auto uccidono. O meglio: la velocit\u00e0 uccide. <br>Il sogno di potenza pu\u00f2 trasformarsi rapidamente in un incubo di morte tra lamiere accartocciate, ma si preferisce non parlarne: la responsabilit\u00e0 di morte attribuibile alla velocit\u00e0 \u00e8 tab\u00f9. <br>Eppure una rilettura creativa di quegli stessi materiali pubblicitari inneggianti alle meraviglie delle auto pu\u00f2 svelarci un paradosso in grado di incrinare il mito sapientemente costruito da chi vendendo macchine ci guadagna. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/motorshow.aplysia.net\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Sito web<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Film di montaggio sui paradossi della velocit\u00e0 alla guida. <br \/>Durata: 5&#8242;<\/p>\n","protected":false},"author":1,"featured_media":413,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[63],"tags":[],"class_list":["post-412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-video"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5&#039;\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Giuseppe Petruzzellis\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Giuseppe Petruzzellis - Filmmaker and artist | Portfolio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"MotorShow (2008) - Giuseppe Petruzzellis\" \/>\n\t\t<meta property=\"og:description\" content=\"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5&#039;\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2008-07-01T16:44:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2023-02-03T14:24:01+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/giuseppe.petruzzellis.35\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"MotorShow (2008) - Giuseppe Petruzzellis\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5&#039;\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#blogposting\",\"name\":\"MotorShow (2008) - Giuseppe Petruzzellis\",\"headline\":\"MotorShow (2008)\",\"author\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/bannerTitolo.jpg\",\"width\":648,\"height\":365},\"datePublished\":\"2008-07-01T17:44:00+01:00\",\"dateModified\":\"2023-02-03T15:24:01+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#webpage\"},\"articleSection\":\"video, Italiano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giuseppepetruzzellis.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/video\\\/#listItem\",\"name\":\"video\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/video\\\/#listItem\",\"position\":2,\"name\":\"video\",\"item\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/video\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#listItem\",\"name\":\"MotorShow (2008)\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#listItem\",\"position\":3,\"name\":\"MotorShow (2008)\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/video\\\/#listItem\",\"name\":\"video\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\",\"name\":\"Giuseppe Petruzzellis\",\"description\":\"Filmmaker and artist | Portfolio\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/giuseppe.petruzzellis.35\",\"https:\\\/\\\/www.instagram.com\\\/giuseppe.petruzzellis\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/\",\"name\":\"Giuseppe Petruzzellis\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd53587ae22f0d6fb6aa4e5024a2ff2ddc6127fc505abfadd5c0ced897c2b6e8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Giuseppe Petruzzellis\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#webpage\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/\",\"name\":\"MotorShow (2008) - Giuseppe Petruzzellis\",\"description\":\"Film di montaggio sui paradossi della velocit\\u00e0 alla guida. Durata: 5'\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/bannerTitolo.jpg\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#mainImage\",\"width\":648,\"height\":365},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2008\\\/07\\\/01\\\/motorshow-2008\\\/#mainImage\"},\"datePublished\":\"2008-07-01T17:44:00+01:00\",\"dateModified\":\"2023-02-03T15:24:01+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#website\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/\",\"name\":\"Giuseppe Petruzzellis\",\"description\":\"Filmmaker and artist | Portfolio\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"MotorShow (2008) - Giuseppe Petruzzellis","description":"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5'","canonical_url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#blogposting","name":"MotorShow (2008) - Giuseppe Petruzzellis","headline":"MotorShow (2008)","author":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"publisher":{"@id":"https:\/\/giuseppepetruzzellis.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg","width":648,"height":365},"datePublished":"2008-07-01T17:44:00+01:00","dateModified":"2023-02-03T15:24:01+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#webpage"},"isPartOf":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#webpage"},"articleSection":"video, Italiano"},{"@type":"BreadcrumbList","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com#listItem","position":1,"name":"Home","item":"https:\/\/giuseppepetruzzellis.com","nextItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/#listItem","name":"video"}},{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/#listItem","position":2,"name":"video","item":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/","nextItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#listItem","name":"MotorShow (2008)"},"previousItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#listItem","position":3,"name":"MotorShow (2008)","previousItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/#listItem","name":"video"}}]},{"@type":"Organization","@id":"https:\/\/giuseppepetruzzellis.com\/#organization","name":"Giuseppe Petruzzellis","description":"Filmmaker and artist | Portfolio","url":"https:\/\/giuseppepetruzzellis.com\/","sameAs":["https:\/\/www.facebook.com\/giuseppe.petruzzellis.35","https:\/\/www.instagram.com\/giuseppe.petruzzellis\/"]},{"@type":"Person","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author","url":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/","name":"Giuseppe Petruzzellis","image":{"@type":"ImageObject","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bd53587ae22f0d6fb6aa4e5024a2ff2ddc6127fc505abfadd5c0ced897c2b6e8?s=96&d=mm&r=g","width":96,"height":96,"caption":"Giuseppe Petruzzellis"}},{"@type":"WebPage","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#webpage","url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/","name":"MotorShow (2008) - Giuseppe Petruzzellis","description":"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5'","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/giuseppepetruzzellis.com\/#website"},"breadcrumb":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#breadcrumblist"},"author":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"creator":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#mainImage","width":648,"height":365},"primaryImageOfPage":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/#mainImage"},"datePublished":"2008-07-01T17:44:00+01:00","dateModified":"2023-02-03T15:24:01+01:00"},{"@type":"WebSite","@id":"https:\/\/giuseppepetruzzellis.com\/#website","url":"https:\/\/giuseppepetruzzellis.com\/","name":"Giuseppe Petruzzellis","description":"Filmmaker and artist | Portfolio","inLanguage":"it-IT","publisher":{"@id":"https:\/\/giuseppepetruzzellis.com\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Giuseppe Petruzzellis - Filmmaker and artist | Portfolio","og:type":"article","og:title":"MotorShow (2008) - Giuseppe Petruzzellis","og:description":"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5'","og:url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/","article:published_time":"2008-07-01T16:44:00+00:00","article:modified_time":"2023-02-03T14:24:01+00:00","article:publisher":"https:\/\/www.facebook.com\/giuseppe.petruzzellis.35","twitter:card":"summary_large_image","twitter:title":"MotorShow (2008) - Giuseppe Petruzzellis","twitter:description":"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5'"},"aioseo_meta_data":{"post_id":"412","title":null,"description":null,"keywords":null,"keyphrases":null,"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":null,"og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":null,"robots_max_videopreview":null,"robots_max_imagepreview":"large","priority":null,"frequency":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2023-03-01 15:05:59","updated":"2025-06-04 07:47:31","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/giuseppepetruzzellis.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/\" title=\"video\">video<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tMotorShow <br>(2008)\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/giuseppepetruzzellis.com"},{"label":"video","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/video\/"},{"label":"MotorShow <br>(2008)","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/2008\/07\/01\/motorshow-2008\/"}],"uagb_featured_image_src":{"full":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg",648,365,false],"thumbnail":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo-150x150.jpg",150,150,true],"medium":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo-300x169.jpg",300,169,true],"medium_large":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg",648,365,false],"large":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg",648,365,false],"1536x1536":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg",648,365,false],"2048x2048":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2023\/01\/bannerTitolo.jpg",648,365,false]},"uagb_author_info":{"display_name":"Giuseppe Petruzzellis","author_link":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/"},"uagb_comment_info":0,"uagb_excerpt":"Film di montaggio sui paradossi della velocit\u00e0 alla guida. Durata: 5'","_links":{"self":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/comments?post=412"}],"version-history":[{"count":3,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/412\/revisions"}],"predecessor-version":[{"id":422,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/412\/revisions\/422"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/media\/413"}],"wp:attachment":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/media?parent=412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/categories?post=412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/tags?post=412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}