{"id":2333,"date":"2025-11-26T14:11:11","date_gmt":"2025-11-26T13:11:11","guid":{"rendered":"https:\/\/giuseppepetruzzellis.com\/?p=2333"},"modified":"2026-02-01T21:24:08","modified_gmt":"2026-02-01T20:24:08","slug":"inner-soundtrack-closed-eyes","status":"publish","type":"post","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/","title":{"rendered":"inner soundtrack &#8211; closed eyes"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Progetto dark ambient \/ soundscape \/ drone. Meditazioni sonore per scene interiori.<\/p>\n\n\n\n<iframe style=\"border: 0; width: 350px; height: 654px;\" src=\"https:\/\/bandcamp.com\/EmbeddedPlayer\/album=4215637850\/size=large\/bgcol=ffffff\/linkcol=7137dc\/transparent=true\/\" seamless><a href=\"https:\/\/innersoundtrack.bandcamp.com\/album\/closed-eyes\">closed eyes by inner soundtrack<\/a><\/iframe>\n\n\n\n<p class=\"wp-block-paragraph\">Ogni composizione \u00e8 affrontata come una \u201cmeditazione sonora\u201d: un rituale di focalizzazione in cui toni, rumori e armoniche diventano guide attraverso un paesaggio mutevole fatto di sensazioni corporee e immagini pre-consce.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le sorgenti sonore alla base di questi brani strumentali spaziano da synth analogici a sound samples e colonne sonore cinematografiche inedite. Queste opere ambient sono al tempo stesso una pratica personale e un invito per l\u2019ascoltatore.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con <em>closed eyes<\/em>, prima release del progetto <em>inner soundtrack<\/em>, i sei pezzi sono concepiti come un unico viaggio da ascoltare in sequenza, a occhi chiusi, come un percorso meditativo: un invito a rallentare, rivolgersi verso l\u2019interno, abbandonarsi al movimento del suono ed esplorare il campo a cavallo tra l\u2019attenzione cosciente e la percezione subliminale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/innersoundtrack.bandcamp.com\/album\/closed-eyes\" target=\"_blank\" rel=\"noopener\" title=\"\"><strong>Link bandcamp<\/strong><\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ambient \/ Experimental<\/p>\n","protected":false},"author":1,"featured_media":2334,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_uag_custom_page_level_css":"","_monsterinsights_skip_tracking":false,"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[28],"tags":[216,218,212],"class_list":["post-2333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-music","tag-colonna-sonora","tag-meditazione","tag-musica"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Ambient \/ Experimental\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Giuseppe Petruzzellis\"\/>\n\t<link rel=\"canonical\" href=\"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"it_IT\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Giuseppe Petruzzellis - Filmmaker and artist | Portfolio\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis\" \/>\n\t\t<meta property=\"og:description\" content=\"Ambient \/ Experimental\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-11-26T13:11:11+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-01T20:24:08+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/giuseppe.petruzzellis.35\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n\t\t<meta name=\"twitter:title\" content=\"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Ambient \/ Experimental\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BlogPosting\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#blogposting\",\"name\":\"inner soundtrack \\u2013 closed eyes - Giuseppe Petruzzellis\",\"headline\":\"inner soundtrack &#8211; closed eyes\",\"author\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pellicola237_v03-scaled.jpg\",\"width\":2560,\"height\":2560},\"datePublished\":\"2025-11-26T14:11:11+01:00\",\"dateModified\":\"2026-02-01T21:24:08+01:00\",\"inLanguage\":\"it-IT\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#webpage\"},\"articleSection\":\"music, colonna sonora, meditazione, musica, Italiano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/giuseppepetruzzellis.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/music\\\/#listItem\",\"name\":\"music\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/music\\\/#listItem\",\"position\":2,\"name\":\"music\",\"item\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/music\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#listItem\",\"name\":\"inner soundtrack &#8211; closed eyes\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#listItem\",\"position\":3,\"name\":\"inner soundtrack &#8211; closed eyes\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/category\\\/music\\\/#listItem\",\"name\":\"music\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\",\"name\":\"Giuseppe Petruzzellis\",\"description\":\"Filmmaker and artist | Portfolio\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/giuseppe.petruzzellis.35\",\"https:\\\/\\\/www.instagram.com\\\/giuseppe.petruzzellis\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/\",\"name\":\"Giuseppe Petruzzellis\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bd53587ae22f0d6fb6aa4e5024a2ff2ddc6127fc505abfadd5c0ced897c2b6e8?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Giuseppe Petruzzellis\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#webpage\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/\",\"name\":\"inner soundtrack \\u2013 closed eyes - Giuseppe Petruzzellis\",\"description\":\"Ambient \\\/ Experimental\",\"inLanguage\":\"it-IT\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/author\\\/gpaplysia-net\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/pellicola237_v03-scaled.jpg\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#mainImage\",\"width\":2560,\"height\":2560},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/index.php\\\/2025\\\/11\\\/26\\\/inner-soundtrack-closed-eyes\\\/#mainImage\"},\"datePublished\":\"2025-11-26T14:11:11+01:00\",\"dateModified\":\"2026-02-01T21:24:08+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#website\",\"url\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/\",\"name\":\"Giuseppe Petruzzellis\",\"description\":\"Filmmaker and artist | Portfolio\",\"inLanguage\":\"it-IT\",\"publisher\":{\"@id\":\"https:\\\/\\\/giuseppepetruzzellis.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis","description":"Ambient \/ Experimental","canonical_url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BlogPosting","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#blogposting","name":"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis","headline":"inner soundtrack &#8211; closed eyes","author":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"publisher":{"@id":"https:\/\/giuseppepetruzzellis.com\/#organization"},"image":{"@type":"ImageObject","url":"https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-scaled.jpg","width":2560,"height":2560},"datePublished":"2025-11-26T14:11:11+01:00","dateModified":"2026-02-01T21:24:08+01:00","inLanguage":"it-IT","mainEntityOfPage":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#webpage"},"isPartOf":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#webpage"},"articleSection":"music, colonna sonora, meditazione, musica, Italiano"},{"@type":"BreadcrumbList","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com#listItem","position":1,"name":"Home","item":"https:\/\/giuseppepetruzzellis.com","nextItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/#listItem","name":"music"}},{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/#listItem","position":2,"name":"music","item":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/","nextItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#listItem","name":"inner soundtrack &#8211; closed eyes"},"previousItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#listItem","position":3,"name":"inner soundtrack &#8211; closed eyes","previousItem":{"@type":"ListItem","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/#listItem","name":"music"}}]},{"@type":"Organization","@id":"https:\/\/giuseppepetruzzellis.com\/#organization","name":"Giuseppe Petruzzellis","description":"Filmmaker and artist | Portfolio","url":"https:\/\/giuseppepetruzzellis.com\/","sameAs":["https:\/\/www.facebook.com\/giuseppe.petruzzellis.35","https:\/\/www.instagram.com\/giuseppe.petruzzellis\/"]},{"@type":"Person","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author","url":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/","name":"Giuseppe Petruzzellis","image":{"@type":"ImageObject","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/bd53587ae22f0d6fb6aa4e5024a2ff2ddc6127fc505abfadd5c0ced897c2b6e8?s=96&d=mm&r=g","width":96,"height":96,"caption":"Giuseppe Petruzzellis"}},{"@type":"WebPage","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#webpage","url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/","name":"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis","description":"Ambient \/ Experimental","inLanguage":"it-IT","isPartOf":{"@id":"https:\/\/giuseppepetruzzellis.com\/#website"},"breadcrumb":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#breadcrumblist"},"author":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"creator":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-scaled.jpg","@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#mainImage","width":2560,"height":2560},"primaryImageOfPage":{"@id":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/#mainImage"},"datePublished":"2025-11-26T14:11:11+01:00","dateModified":"2026-02-01T21:24:08+01:00"},{"@type":"WebSite","@id":"https:\/\/giuseppepetruzzellis.com\/#website","url":"https:\/\/giuseppepetruzzellis.com\/","name":"Giuseppe Petruzzellis","description":"Filmmaker and artist | Portfolio","inLanguage":"it-IT","publisher":{"@id":"https:\/\/giuseppepetruzzellis.com\/#organization"}}]},"og:locale":"it_IT","og:site_name":"Giuseppe Petruzzellis - Filmmaker and artist | Portfolio","og:type":"article","og:title":"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis","og:description":"Ambient \/ Experimental","og:url":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/","article:published_time":"2025-11-26T13:11:11+00:00","article:modified_time":"2026-02-01T20:24:08+00:00","article:publisher":"https:\/\/www.facebook.com\/giuseppe.petruzzellis.35","twitter:card":"summary_large_image","twitter:title":"inner soundtrack \u2013 closed eyes - Giuseppe Petruzzellis","twitter:description":"Ambient \/ Experimental"},"aioseo_meta_data":{"post_id":"2333","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"BlogPosting","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-11-26 13:11:14","updated":"2026-02-01 20:38:14","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/giuseppepetruzzellis.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/\" title=\"music\">music<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tinner soundtrack \u2013 closed eyes\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/giuseppepetruzzellis.com"},{"label":"music","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/category\/music\/"},{"label":"inner soundtrack &#8211; closed eyes","link":"https:\/\/giuseppepetruzzellis.com\/index.php\/2025\/11\/26\/inner-soundtrack-closed-eyes\/"}],"uagb_featured_image_src":{"full":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-scaled.jpg",2560,2560,false],"thumbnail":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-150x150.jpg",150,150,true],"medium":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-300x300.jpg",300,300,true],"medium_large":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-768x768.jpg",768,768,true],"large":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-1024x1024.jpg",1024,1024,true],"1536x1536":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-1536x1536.jpg",1536,1536,true],"2048x2048":["https:\/\/giuseppepetruzzellis.com\/wp-content\/uploads\/2025\/11\/pellicola237_v03-2048x2048.jpg",2048,2048,true]},"uagb_author_info":{"display_name":"Giuseppe Petruzzellis","author_link":"https:\/\/giuseppepetruzzellis.com\/index.php\/author\/gpaplysia-net\/"},"uagb_comment_info":0,"uagb_excerpt":"Ambient \/ Experimental","_links":{"self":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/2333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/comments?post=2333"}],"version-history":[{"count":6,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions"}],"predecessor-version":[{"id":2380,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/posts\/2333\/revisions\/2380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/media\/2334"}],"wp:attachment":[{"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/media?parent=2333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/categories?post=2333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/giuseppepetruzzellis.com\/index.php\/wp-json\/wp\/v2\/tags?post=2333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}